{"id":144,"count":1,"description":"","link":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/","name":"dental implant procedure price","slug":"dental-implant-procedure-price","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>dental implant procedure price Archives - Roberto Macedo, DDS, MS, PHD<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dental implant procedure price Archives - Roberto Macedo, DDS, MS, PHD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/\" \/>\n<meta property=\"og:site_name\" content=\"Roberto Macedo, DDS, MS, PHD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/\",\"url\":\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/\",\"name\":\"dental implant procedure price Archives - Roberto Macedo, DDS, MS, PHD\",\"isPartOf\":{\"@id\":\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"dental implant procedure price\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/#website\",\"url\":\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/\",\"name\":\"Roberto Macedo, DDS, MS, PHD\",\"description\":\"Dentist in St. Petersburg | Dentist 33710\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"dental implant procedure price Archives - Roberto Macedo, DDS, MS, PHD","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"dental implant procedure price Archives - Roberto Macedo, DDS, MS, PHD","og_url":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/","og_site_name":"Roberto Macedo, DDS, MS, PHD","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/","url":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/","name":"dental implant procedure price Archives - Roberto Macedo, DDS, MS, PHD","isPartOf":{"@id":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/tag\/dental-implant-procedure-price\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/"},{"@type":"ListItem","position":2,"name":"dental implant procedure price"}]},{"@type":"WebSite","@id":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/#website","url":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/","name":"Roberto Macedo, DDS, MS, PHD","description":"Dentist in St. Petersburg | Dentist 33710","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/wp-json\/wp\/v2\/tags\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/advancedcenterforcosmeticdentistry.com\/blog\/wp-json\/wp\/v2\/posts?tags=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}